{"id":894,"date":"2014-04-22T14:37:28","date_gmt":"2014-04-22T13:37:28","guid":{"rendered":"http:\/\/domainedetrestraou.com\/es\/foire-aux-questions\/"},"modified":"2021-04-30T10:50:09","modified_gmt":"2021-04-30T09:50:09","slug":"preguntas-frecuentes","status":"publish","type":"page","link":"https:\/\/domainedetrestraou.com\/es\/preguntas-frecuentes\/","title":{"rendered":"Preguntas frecuentes"},"content":{"rendered":"<h3>\u00bfHay piscina?<\/h3>\n<p>Disponemos de una piscina de aprendizaje (clases de nataci\u00f3n) climatizada y descubierta.<br \/>\nAparte de eso y por el momento, nuestra piscina m\u00e1s grande es&#8230; <strong>\u00a1el mar <\/strong>que tenemos a 100 metros! \u00a1Excelente para la salud!<\/p>\n<h3>\u00bfHay actividades para los ni\u00f1os?<\/h3>\n<p>Organizamos juegos al aire libre y disponemos de una sala de juegos y televisi\u00f3n vigilada por padres.<br \/>\nEn la playa hay numerosas actividades para los ni\u00f1os programadas para medio d\u00eda, un d\u00eda entero o una semana, \u00a1para entretenerlos sin preocupaciones!<\/p>\n<h3>Alquileres: \u00bfEst\u00e1 todo incluido?<\/h3>\n<p>No olvide traer ropa de cama, toallas, y trapos de cocina. (s\u00e1banas, fundas de almohadas cuadradas y alargadas, toallas y trapos de cocina). Tambi\u00e9n ofrecemos la posibilidad de alquilar estos art\u00edculos.<\/p>\n<h3>\u00bfA partir de qu\u00e9 hora se puede llegar \/ salir?<\/h3>\n<p>En el caso de las parcelas libres, las noches se cuentan de 12:00 a 12:00 del mediod\u00eda.<br \/>\nEn el caso de los alquileres (bungal\u00f3s y mobile-homes), se aceptan llegadas a partir de las 16:00 h y salidas hasta las 10:00 h.<\/p>\n<h3><span lang=\"ES\">\u00bfCu\u00e1ndo hay que reservar en el Domaine de Trestraou?<\/span><\/h3>\n<p><span lang=\"ES\">Lo antes posible, \u00a1por supuesto!<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfHay piscina? Disponemos de una piscina de aprendizaje (clases de nataci\u00f3n) climatizada y descubierta. Aparte de eso y por el momento, nuestra piscina m\u00e1s grande es&#8230; \u00a1el mar que tenemos a 100 metros! \u00a1Excelente para la salud! \u00bfHay actividades para los ni\u00f1os? Organizamos juegos al aire libre y disponemos de una sala de juegos y [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-894","page","type-page","status-publish","hentry"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Si tiene cualquier duda sobre la organizaci\u00f3n, nuestros equipamientos o las normas de convivencia\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/domainedetrestraou.com\/es\/preguntas-frecuentes\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/domainedetrestraou.com\\\/es\\\/preguntas-frecuentes\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/domainedetrestraou.com\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/domainedetrestraou.com\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/domainedetrestraou.com\\\/es\\\/preguntas-frecuentes\\\/#listItem\",\"name\":\"Preguntas frecuentes\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/domainedetrestraou.com\\\/es\\\/preguntas-frecuentes\\\/#listItem\",\"position\":2,\"name\":\"Preguntas frecuentes\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/domainedetrestraou.com\\\/es\\\/#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/domainedetrestraou.com\\\/es\\\/#organization\",\"name\":\"Domaine de Trestraou\",\"description\":\"l'h\\u00f4tellerie de plein air \\u00e0 Perros Guirec\",\"url\":\"https:\\\/\\\/domainedetrestraou.com\\\/es\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/domainedetrestraou.com\\\/es\\\/preguntas-frecuentes\\\/#webpage\",\"url\":\"https:\\\/\\\/domainedetrestraou.com\\\/es\\\/preguntas-frecuentes\\\/\",\"name\":\"Todas las respuestas a sus preguntas | Domaine de Trestraou\",\"description\":\"Si tiene cualquier duda sobre la organizaci\\u00f3n, nuestros equipamientos o las normas de convivencia\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/domainedetrestraou.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/domainedetrestraou.com\\\/es\\\/preguntas-frecuentes\\\/#breadcrumblist\"},\"datePublished\":\"2014-04-22T14:37:28+01:00\",\"dateModified\":\"2021-04-30T10:50:09+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/domainedetrestraou.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/domainedetrestraou.com\\\/es\\\/\",\"name\":\"Domaine de Trestraou\",\"description\":\"l'h\\u00f4tellerie de plein air \\u00e0 Perros Guirec\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/domainedetrestraou.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Todas las respuestas a sus preguntas | Domaine de Trestraou","description":"Si tiene cualquier duda sobre la organizaci\u00f3n, nuestros equipamientos o las normas de convivencia","canonical_url":"https:\/\/domainedetrestraou.com\/es\/preguntas-frecuentes\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/domainedetrestraou.com\/es\/preguntas-frecuentes\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/domainedetrestraou.com\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/domainedetrestraou.com\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/domainedetrestraou.com\/es\/preguntas-frecuentes\/#listItem","name":"Preguntas frecuentes"}},{"@type":"ListItem","@id":"https:\/\/domainedetrestraou.com\/es\/preguntas-frecuentes\/#listItem","position":2,"name":"Preguntas frecuentes","previousItem":{"@type":"ListItem","@id":"https:\/\/domainedetrestraou.com\/es\/#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/domainedetrestraou.com\/es\/#organization","name":"Domaine de Trestraou","description":"l'h\u00f4tellerie de plein air \u00e0 Perros Guirec","url":"https:\/\/domainedetrestraou.com\/es\/"},{"@type":"WebPage","@id":"https:\/\/domainedetrestraou.com\/es\/preguntas-frecuentes\/#webpage","url":"https:\/\/domainedetrestraou.com\/es\/preguntas-frecuentes\/","name":"Todas las respuestas a sus preguntas | Domaine de Trestraou","description":"Si tiene cualquier duda sobre la organizaci\u00f3n, nuestros equipamientos o las normas de convivencia","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/domainedetrestraou.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/domainedetrestraou.com\/es\/preguntas-frecuentes\/#breadcrumblist"},"datePublished":"2014-04-22T14:37:28+01:00","dateModified":"2021-04-30T10:50:09+01:00"},{"@type":"WebSite","@id":"https:\/\/domainedetrestraou.com\/es\/#website","url":"https:\/\/domainedetrestraou.com\/es\/","name":"Domaine de Trestraou","description":"l'h\u00f4tellerie de plein air \u00e0 Perros Guirec","inLanguage":"es-ES","publisher":{"@id":"https:\/\/domainedetrestraou.com\/es\/#organization"}}]}},"aioseo_meta_data":{"post_id":"894","title":"Todas las respuestas a sus preguntas | #site_title","description":"Si tiene cualquier duda sobre la organizaci\u00f3n, nuestros equipamientos o las normas de convivencia","keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-05-20 16:52:02","updated":"2025-09-08 16:43:39","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/domainedetrestraou.com\/es\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tPreguntas frecuentes\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/domainedetrestraou.com\/es\/"},{"label":"Preguntas frecuentes","link":"https:\/\/domainedetrestraou.com\/es\/preguntas-frecuentes\/"}],"_links":{"self":[{"href":"https:\/\/domainedetrestraou.com\/es\/wp-json\/wp\/v2\/pages\/894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/domainedetrestraou.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/domainedetrestraou.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/domainedetrestraou.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/domainedetrestraou.com\/es\/wp-json\/wp\/v2\/comments?post=894"}],"version-history":[{"count":8,"href":"https:\/\/domainedetrestraou.com\/es\/wp-json\/wp\/v2\/pages\/894\/revisions"}],"predecessor-version":[{"id":1790,"href":"https:\/\/domainedetrestraou.com\/es\/wp-json\/wp\/v2\/pages\/894\/revisions\/1790"}],"wp:attachment":[{"href":"https:\/\/domainedetrestraou.com\/es\/wp-json\/wp\/v2\/media?parent=894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}